{"id":65812,"date":"2026-03-19T12:51:43","date_gmt":"2026-03-19T12:51:43","guid":{"rendered":"https:\/\/www.tappx.com\/events\/pocket-gamer-connects-barcelona-2026-es"},"modified":"2026-03-19T13:05:32","modified_gmt":"2026-03-19T13:05:32","slug":"pocket-gamer-connects-barcelona-2026","status":"publish","type":"cpt_events","link":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026","title":{"rendered":"Pocket Gamer Connects Barcelona 2026"},"content":{"rendered":"<p>Pocket Gamer Connects Barcelona 2026 es una conferencia internacional dedicada a la industria global del gaming que re\u00fane a desarrolladores, publishers, inversores y proveedores tecnol\u00f3gicos en uno de los hubs de videojuegos de mayor crecimiento en Europa. El evento cuenta con un programa de m\u00faltiples tracks que abordan temas como el gaming en m\u00f3vil, PC y consola, as\u00ed como tecnolog\u00edas emergentes como la inteligencia artificial, XR y HTML5. Los asistentes podr\u00e1n conocer tendencias del sector, descubrir oportunidades de negocio y conectar con profesionales de todo el ecosistema del gaming.<\/p>\n","protected":false},"excerpt":{"rendered":"Pocket Gamer Connects Barcelona 2026 es una conferencia internacional dedicada a la industria global del gaming que re\u00fane a desarrolladores, publishers, inversores y proveedores tecnol\u00f3gicos en uno de los hubs de videojuegos de mayor crecimiento en Europa. El evento cuenta con un programa de m\u00faltiples tracks que abordan temas como el gaming en m\u00f3vil, PC&#8230; <a class=\"view-article\" href=\"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026\">View Article<\/a>","protected":false},"featured_media":64163,"parent":0,"menu_order":0,"template":"","tax_category_events":[862,860,861],"tax_localizacion":[535],"tax_organizacion":[807],"tax_brand_events":[],"class_list":["post-65812","cpt_events","type-cpt_events","status-publish","has-post-thumbnail","hentry","tax_category_events-gaming-es","tax_category_events-mobile-es","tax_category_events-tecnologia","tax_localizacion-espana","tax_organizacion-pocket-gamer-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pocket Gamer Connects Barcelona 2026 | Tappx<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pocket Gamer Connects Barcelona 2026 | Tappx\" \/>\n<meta property=\"og:description\" content=\"Pocket Gamer Connects Barcelona 2026 es una conferencia internacional dedicada a la industria global del gaming que re\u00fane a desarrolladores, publishers, inversores y proveedores tecnol\u00f3gicos en uno de los hubs de videojuegos de mayor crecimiento en Europa. El evento cuenta con un programa de m\u00faltiples tracks que abordan temas como el gaming en m\u00f3vil, PC... View Article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026\" \/>\n<meta property=\"og:site_name\" content=\"Tappx\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-19T13:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tappx.com\/wp-content\/uploads\/2025\/10\/pocker_gamer_connects-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026\",\"url\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026\",\"name\":\"Pocket Gamer Connects Barcelona 2026 | Tappx\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tappx.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pocker_gamer_connects-1.jpg\",\"datePublished\":\"2026-03-19T12:51:43+00:00\",\"dateModified\":\"2026-03-19T13:05:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026#primaryimage\",\"url\":\"https:\\\/\\\/www.tappx.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pocker_gamer_connects-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tappx.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pocker_gamer_connects-1.jpg\",\"width\":760,\"height\":436},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\\\/pocket-gamer-connects-barcelona-2026#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tappx.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.tappx.com\\\/es\\\/eventos\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pocket Gamer Connects Barcelona 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es#website\",\"url\":\"https:\\\/\\\/www.tappx.com\\\/es\",\"name\":\"Tappx\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tappx.com\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es#organization\",\"name\":\"Tappx\",\"url\":\"https:\\\/\\\/www.tappx.com\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Tappx\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tappx.com\\\/es#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pocket Gamer Connects Barcelona 2026 | Tappx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026","og_locale":"es_ES","og_type":"article","og_title":"Pocket Gamer Connects Barcelona 2026 | Tappx","og_description":"Pocket Gamer Connects Barcelona 2026 es una conferencia internacional dedicada a la industria global del gaming que re\u00fane a desarrolladores, publishers, inversores y proveedores tecnol\u00f3gicos en uno de los hubs de videojuegos de mayor crecimiento en Europa. El evento cuenta con un programa de m\u00faltiples tracks que abordan temas como el gaming en m\u00f3vil, PC... View Article","og_url":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026","og_site_name":"Tappx","article_modified_time":"2026-03-19T13:05:32+00:00","og_image":[{"width":760,"height":436,"url":"https:\/\/www.tappx.com\/wp-content\/uploads\/2025\/10\/pocker_gamer_connects-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026","url":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026","name":"Pocket Gamer Connects Barcelona 2026 | Tappx","isPartOf":{"@id":"https:\/\/www.tappx.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026#primaryimage"},"image":{"@id":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026#primaryimage"},"thumbnailUrl":"https:\/\/www.tappx.com\/wp-content\/uploads\/2025\/10\/pocker_gamer_connects-1.jpg","datePublished":"2026-03-19T12:51:43+00:00","dateModified":"2026-03-19T13:05:32+00:00","breadcrumb":{"@id":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026#primaryimage","url":"https:\/\/www.tappx.com\/wp-content\/uploads\/2025\/10\/pocker_gamer_connects-1.jpg","contentUrl":"https:\/\/www.tappx.com\/wp-content\/uploads\/2025\/10\/pocker_gamer_connects-1.jpg","width":760,"height":436},{"@type":"BreadcrumbList","@id":"https:\/\/www.tappx.com\/es\/eventos\/pocket-gamer-connects-barcelona-2026#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tappx.com\/es"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.tappx.com\/es\/eventos"},{"@type":"ListItem","position":3,"name":"Pocket Gamer Connects Barcelona 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.tappx.com\/es#website","url":"https:\/\/www.tappx.com\/es","name":"Tappx","description":"","publisher":{"@id":"https:\/\/www.tappx.com\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tappx.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.tappx.com\/es#organization","name":"Tappx","url":"https:\/\/www.tappx.com\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tappx.com\/es#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Tappx"},"image":{"@id":"https:\/\/www.tappx.com\/es#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/cpt_events\/65812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/cpt_events"}],"about":[{"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/types\/cpt_events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/media\/64163"}],"wp:attachment":[{"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/media?parent=65812"}],"wp:term":[{"taxonomy":"tax_category_events","embeddable":true,"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/tax_category_events?post=65812"},{"taxonomy":"tax_localizacion","embeddable":true,"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/tax_localizacion?post=65812"},{"taxonomy":"tax_organizacion","embeddable":true,"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/tax_organizacion?post=65812"},{"taxonomy":"tax_brand_events","embeddable":true,"href":"https:\/\/www.tappx.com\/es\/wp-json\/wp\/v2\/tax_brand_events?post=65812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}